{"id":23593,"date":"2025-02-10T13:33:44","date_gmt":"2025-02-10T12:33:44","guid":{"rendered":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3.png"},"modified":"2025-02-10T13:33:44","modified_gmt":"2025-02-10T12:33:44","slug":"hessische-meisterschaft-3-2","status":"inherit","type":"attachment","link":"https:\/\/swisswrestling.ch\/fr\/hessische-meisterschaft-3-2\/","title":{"rendered":"Hessische Meisterschaft 3"},"author":7,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":[],"class_list":["post-23593","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-300x300.png 300w, https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-1024x1024.png 1024w, https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-150x150.png 150w, https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-768x768.png 768w, https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1080,"height":1080,"file":"2025\/02\/Hessische-Meisterschaft-3.png","filesize":1784981,"sizes":{"medium":{"file":"Hessische-Meisterschaft-3-300x300.png","width":300,"height":300,"filesize":118782,"mime_type":"image\/png","source_url":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-300x300.png"},"large":{"file":"Hessische-Meisterschaft-3-1024x1024.png","width":1024,"height":1024,"filesize":1134230,"mime_type":"image\/png","source_url":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-1024x1024.png"},"thumbnail":{"file":"Hessische-Meisterschaft-3-150x150.png","width":150,"height":150,"filesize":34642,"mime_type":"image\/png","source_url":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-150x150.png"},"medium_large":{"file":"Hessische-Meisterschaft-3-768x768.png","width":768,"height":768,"filesize":669591,"mime_type":"image\/png","source_url":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3-768x768.png"},"full":{"file":"Hessische-Meisterschaft-3.png","width":1080,"height":1080,"mime_type":"image\/png","source_url":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/swisswrestling.ch\/wp-content\/uploads\/2025\/02\/Hessische-Meisterschaft-3.png","_links":{"self":[{"href":"https:\/\/swisswrestling.ch\/fr\/wp-json\/wp\/v2\/media\/23593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisswrestling.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/swisswrestling.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/swisswrestling.ch\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/swisswrestling.ch\/fr\/wp-json\/wp\/v2\/comments?post=23593"}]}}